{"id":5,"count":17,"description":"","link":"https:\/\/lizzycare.com\/resources\/category\/care-at-home\/","name":"Care at home","slug":"care-at-home","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/lizzycare.com\/resources\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lizzycare.com\/resources\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lizzycare.com\/resources\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lizzycare.com\/resources\/wp-json\/wp\/v2\/posts?categories=5"},{"href":"https:\/\/lizzycare.com\/resources\/wp-json\/wp\/v2\/courses?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}